{"id":70,"count":2,"description":"","link":"https:\/\/gavelsabogados.com\/en\/category\/commercial-law\/","name":"Commercial law","slug":"commercial-law","taxonomy":"category","parent":0,"meta":[],"yoast_head":"\n<title>Commercial law archivos - GAVELS ABOGADOS<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/gavelsabogados.com\/en\/category\/commercial-law\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Commercial law archivos - GAVELS ABOGADOS\" \/>\n<meta property=\"og:url\" content=\"https:\/\/gavelsabogados.com\/en\/category\/commercial-law\/\" \/>\n<meta property=\"og:site_name\" content=\"GAVELS ABOGADOS\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/gavelsabogados.com\/en\/category\/commercial-law\/\",\"url\":\"https:\/\/gavelsabogados.com\/en\/category\/commercial-law\/\",\"name\":\"Commercial law archivos - GAVELS ABOGADOS\",\"isPartOf\":{\"@id\":\"https:\/\/gavelsabogados.com\/en\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/gavelsabogados.com\/en\/category\/commercial-law\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/gavelsabogados.com\/en\/category\/commercial-law\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/gavelsabogados.com\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Commercial law\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/gavelsabogados.com\/en\/#website\",\"url\":\"https:\/\/gavelsabogados.com\/en\/\",\"name\":\"GAVELS ABOGADOS\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/gavelsabogados.com\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/gavelsabogados.com\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/gavelsabogados.com\/en\/#organization\",\"name\":\"Gavels Abogados\",\"url\":\"https:\/\/gavelsabogados.com\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/gavelsabogados.com\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/gavelsabogados.com\/wp-content\/uploads\/2025\/03\/logo_gavels_abogados.png\",\"contentUrl\":\"https:\/\/gavelsabogados.com\/wp-content\/uploads\/2025\/03\/logo_gavels_abogados.png\",\"width\":696,\"height\":696,\"caption\":\"Gavels Abogados\"},\"image\":{\"@id\":\"https:\/\/gavelsabogados.com\/en\/#\/schema\/logo\/image\/\"}}]}<\/script>\n","yoast_head_json":{"title":"Commercial law archivos - GAVELS ABOGADOS","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/gavelsabogados.com\/en\/category\/commercial-law\/","og_locale":"en_US","og_type":"article","og_title":"Commercial law archivos - GAVELS ABOGADOS","og_url":"https:\/\/gavelsabogados.com\/en\/category\/commercial-law\/","og_site_name":"GAVELS ABOGADOS","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/gavelsabogados.com\/en\/category\/commercial-law\/","url":"https:\/\/gavelsabogados.com\/en\/category\/commercial-law\/","name":"Commercial law archivos - GAVELS ABOGADOS","isPartOf":{"@id":"https:\/\/gavelsabogados.com\/en\/#website"},"breadcrumb":{"@id":"https:\/\/gavelsabogados.com\/en\/category\/commercial-law\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/gavelsabogados.com\/en\/category\/commercial-law\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/gavelsabogados.com\/en\/"},{"@type":"ListItem","position":2,"name":"Commercial law"}]},{"@type":"WebSite","@id":"https:\/\/gavelsabogados.com\/en\/#website","url":"https:\/\/gavelsabogados.com\/en\/","name":"GAVELS ABOGADOS","description":"","publisher":{"@id":"https:\/\/gavelsabogados.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/gavelsabogados.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/gavelsabogados.com\/en\/#organization","name":"Gavels Abogados","url":"https:\/\/gavelsabogados.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/gavelsabogados.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/gavelsabogados.com\/wp-content\/uploads\/2025\/03\/logo_gavels_abogados.png","contentUrl":"https:\/\/gavelsabogados.com\/wp-content\/uploads\/2025\/03\/logo_gavels_abogados.png","width":696,"height":696,"caption":"Gavels Abogados"},"image":{"@id":"https:\/\/gavelsabogados.com\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/gavelsabogados.com\/en\/wp-json\/wp\/v2\/categories\/70","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gavelsabogados.com\/en\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/gavelsabogados.com\/en\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/gavelsabogados.com\/en\/wp-json\/wp\/v2\/posts?categories=70"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}<!-- This website is optimized by Airlift. Learn more: https://airlift.net. Template:. Learn more: https://airlift.net. Template: 68c15cd7db888a70abe04d89. Config Timestamp: 2025-09-10 11:11:13 UTC, Cached Timestamp: 2026-05-13 18:07:06 UTC -->